{"id":18494,"date":"2020-04-29T10:43:08","date_gmt":"2020-04-29T08:43:08","guid":{"rendered":"https:\/\/stampenmedia.se\/kampanj\/?p=18494"},"modified":"2020-04-29T10:45:04","modified_gmt":"2020-04-29T08:45:04","slug":"gokboet","status":"publish","type":"post","link":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/","title":{"rendered":"Vecka 18 &#8211; G\u00f6kboet"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;helagbg&#8221; _builder_version=&#8221;3.21.1&#8243; custom_margin=&#8221;|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221;][et_pb_row use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; custom_margin=&#8221;||60px||false|false&#8221; _builder_version=&#8221;3.21.1&#8243; background_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/stampenmedia.se\/kampanj\/wp-content\/uploads\/2020\/04\/gokboet.jpg&#8221; align=&#8221;center&#8221; _builder_version=&#8221;3.21.1&#8243; max_width=&#8221;50%&#8221; max_width_tablet=&#8221;60%&#8221; max_width_phone=&#8221;70%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;31px||-6px&#8221; custom_margin_phone=&#8221;20px||-12px&#8221; custom_margin_last_edited=&#8221;on|phone&#8221;][\/et_pb_image][et_pb_image _builder_version=&#8221;3.21.1&#8243;][\/et_pb_image][et_pb_text module_class=&#8221;helagbg-desc&#8221; _builder_version=&#8221;3.21.1&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_line_height=&#8221;1.4em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#000000&#8243; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;21px&#8221; custom_margin=&#8221;||2px&#8221; custom_padding=&#8221;|30px|0px|30px&#8221;]<\/p>\n<p style=\"text-align: center;\"><span>M\u00e5ndag \u2013 fredag, 9.00 \u2013 21.00<\/span><br \/> <span>L\u00f6rdag \u2013 s\u00f6ndag, 9.00 \u2013 21.00<\/span><\/p>\n<p style=\"text-align: center;\"><span><\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;3.21.1&#8243; max_width=&#8221;71%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-8px&#8221; custom_padding=&#8221;||0px&#8221;][\/et_pb_divider][et_pb_text module_class=&#8221;helagbg2-desc&#8221; _builder_version=&#8221;3.21.1&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_line_height=&#8221;1.4em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#000000&#8243; custom_margin=&#8221;||-16px&#8221; custom_padding=&#8221;|30px|0px|30px&#8221;]<\/p>\n<p style=\"text-align: center;\"><span>Exportgatan 7, Hisings Backa<br \/> 031-52 75 27<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/gokboet.se\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Bes\u00f6k v\u00e5r hemsida h\u00e4r&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;3.21.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#DC3C73&#8243; button_border_width=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; custom_margin=&#8221;20px||30px||false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|false|false&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;helagbg&#8221; _builder_version=&#8221;3.21.1&#8243; custom_margin=&#8221;|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221;][et_pb_row use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; custom_margin=&#8221;||60px||false|false&#8221; _builder_version=&#8221;3.21.1&#8243; background_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/stampenmedia.se\/kampanj\/wp-content\/uploads\/2020\/04\/gokboet.jpg&#8221; align=&#8221;center&#8221; _builder_version=&#8221;3.21.1&#8243; max_width=&#8221;50%&#8221; max_width_tablet=&#8221;60%&#8221; max_width_phone=&#8221;70%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;31px||-6px&#8221; custom_margin_phone=&#8221;20px||-12px&#8221; custom_margin_last_edited=&#8221;on|phone&#8221;][\/et_pb_image][et_pb_image _builder_version=&#8221;3.21.1&#8243;][\/et_pb_image][et_pb_text module_class=&#8221;helagbg-desc&#8221; _builder_version=&#8221;3.21.1&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_line_height=&#8221;1.4em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#000000&#8243; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;21px&#8221; custom_margin=&#8221;||2px&#8221; custom_padding=&#8221;|30px|0px|30px&#8221;] M\u00e5ndag \u2013 fredag, 9.00 \u2013 21.00 L\u00f6rdag \u2013 s\u00f6ndag, 9.00 \u2013 21.00 [\/et_pb_text][et_pb_divider _builder_version=&#8221;3.21.1&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[90,77],"tags":[],"class_list":["post-18494","post","type-post","status-publish","format-standard","hentry","category-v18-7","category-v18event"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vecka 18 - G\u00f6kboet - Kampanj<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vecka 18 - G\u00f6kboet - Kampanj\" \/>\n<meta property=\"og:description\" content=\"[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;helagbg&#8221; _builder_version=&#8221;3.21.1&#8243; custom_margin=&#8221;|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221;][et_pb_row use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; custom_margin=&#8221;||60px||false|false&#8221; _builder_version=&#8221;3.21.1&#8243; background_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/stampenmedia.se\/kampanj\/wp-content\/uploads\/2020\/04\/gokboet.jpg&#8221; align=&#8221;center&#8221; _builder_version=&#8221;3.21.1&#8243; max_width=&#8221;50%&#8221; max_width_tablet=&#8221;60%&#8221; max_width_phone=&#8221;70%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;31px||-6px&#8221; custom_margin_phone=&#8221;20px||-12px&#8221; custom_margin_last_edited=&#8221;on|phone&#8221;][\/et_pb_image][et_pb_image _builder_version=&#8221;3.21.1&#8243;][\/et_pb_image][et_pb_text module_class=&#8221;helagbg-desc&#8221; _builder_version=&#8221;3.21.1&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_line_height=&#8221;1.4em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#000000&#8243; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;21px&#8221; custom_margin=&#8221;||2px&#8221; custom_padding=&#8221;|30px|0px|30px&#8221;] M\u00e5ndag \u2013 fredag, 9.00 \u2013 21.00 L\u00f6rdag \u2013 s\u00f6ndag, 9.00 \u2013 21.00 [\/et_pb_text][et_pb_divider _builder_version=&#8221;3.21.1&#8243; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/\" \/>\n<meta property=\"og:site_name\" content=\"Kampanj\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-29T08:43:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-29T08:45:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stampenmedia.se\/kampanj\/wp-content\/uploads\/2020\/09\/Ska\u0308rmavbild-2020-09-22-kl.-09.49.34.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2656\" \/>\n\t<meta property=\"og:image:height\" content=\"1432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kampanj\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skriven av\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kampanj\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/\"},\"author\":{\"name\":\"Kampanj\",\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/#\\\/schema\\\/person\\\/3d717e3e2240017f1ba57d4ac2986547\"},\"headline\":\"Vecka 18 &#8211; G\u00f6kboet\",\"datePublished\":\"2020-04-29T08:43:08+00:00\",\"dateModified\":\"2020-04-29T08:45:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/\"},\"wordCount\":316,\"commentCount\":0,\"articleSection\":[\"v18-7\",\"v18Event\"],\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/\",\"url\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/\",\"name\":\"Vecka 18 - G\u00f6kboet - Kampanj\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/#website\"},\"datePublished\":\"2020-04-29T08:43:08+00:00\",\"dateModified\":\"2020-04-29T08:45:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/#\\\/schema\\\/person\\\/3d717e3e2240017f1ba57d4ac2986547\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/2020\\\/04\\\/29\\\/gokboet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/helagbg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vecka 18 &#8211; G\u00f6kboet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/#website\",\"url\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/\",\"name\":\"Kampanj\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/#\\\/schema\\\/person\\\/3d717e3e2240017f1ba57d4ac2986547\",\"name\":\"Kampanj\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f7b289b694f164f9db9137f0738b2d73f6edf4cf60aa01f4dbc20313e57eb3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f7b289b694f164f9db9137f0738b2d73f6edf4cf60aa01f4dbc20313e57eb3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/19f7b289b694f164f9db9137f0738b2d73f6edf4cf60aa01f4dbc20313e57eb3?s=96&d=mm&r=g\",\"caption\":\"Kampanj\"},\"url\":\"https:\\\/\\\/stampenmedia.se\\\/kampanj\\\/author\\\/kampanj\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vecka 18 - G\u00f6kboet - Kampanj","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/","og_locale":"sv_SE","og_type":"article","og_title":"Vecka 18 - G\u00f6kboet - Kampanj","og_description":"[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;helagbg&#8221; _builder_version=&#8221;3.21.1&#8243; custom_margin=&#8221;|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221;][et_pb_row use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; custom_margin=&#8221;||60px||false|false&#8221; _builder_version=&#8221;3.21.1&#8243; background_color=&#8221;#ffffff&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/stampenmedia.se\/kampanj\/wp-content\/uploads\/2020\/04\/gokboet.jpg&#8221; align=&#8221;center&#8221; _builder_version=&#8221;3.21.1&#8243; max_width=&#8221;50%&#8221; max_width_tablet=&#8221;60%&#8221; max_width_phone=&#8221;70%&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;31px||-6px&#8221; custom_margin_phone=&#8221;20px||-12px&#8221; custom_margin_last_edited=&#8221;on|phone&#8221;][\/et_pb_image][et_pb_image _builder_version=&#8221;3.21.1&#8243;][\/et_pb_image][et_pb_text module_class=&#8221;helagbg-desc&#8221; _builder_version=&#8221;3.21.1&#8243; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#000000&#8243; text_line_height=&#8221;1.4em&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#000000&#8243; header_2_font=&#8221;||||||||&#8221; header_2_font_size=&#8221;21px&#8221; custom_margin=&#8221;||2px&#8221; custom_padding=&#8221;|30px|0px|30px&#8221;] M\u00e5ndag \u2013 fredag, 9.00 \u2013 21.00 L\u00f6rdag \u2013 s\u00f6ndag, 9.00 \u2013 21.00 [\/et_pb_text][et_pb_divider _builder_version=&#8221;3.21.1&#8243; [&hellip;]","og_url":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/","og_site_name":"Kampanj","article_published_time":"2020-04-29T08:43:08+00:00","article_modified_time":"2020-04-29T08:45:04+00:00","og_image":[{"width":2656,"height":1432,"url":"https:\/\/stampenmedia.se\/kampanj\/wp-content\/uploads\/2020\/09\/Ska\u0308rmavbild-2020-09-22-kl.-09.49.34.png","type":"image\/png"}],"author":"Kampanj","twitter_card":"summary_large_image","twitter_misc":{"Skriven av":"Kampanj","Ber\u00e4knad l\u00e4stid":"2 minuter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/#article","isPartOf":{"@id":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/"},"author":{"name":"Kampanj","@id":"https:\/\/stampenmedia.se\/kampanj\/#\/schema\/person\/3d717e3e2240017f1ba57d4ac2986547"},"headline":"Vecka 18 &#8211; G\u00f6kboet","datePublished":"2020-04-29T08:43:08+00:00","dateModified":"2020-04-29T08:45:04+00:00","mainEntityOfPage":{"@id":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/"},"wordCount":316,"commentCount":0,"articleSection":["v18-7","v18Event"],"inLanguage":"sv-SE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/","url":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/","name":"Vecka 18 - G\u00f6kboet - Kampanj","isPartOf":{"@id":"https:\/\/stampenmedia.se\/kampanj\/#website"},"datePublished":"2020-04-29T08:43:08+00:00","dateModified":"2020-04-29T08:45:04+00:00","author":{"@id":"https:\/\/stampenmedia.se\/kampanj\/#\/schema\/person\/3d717e3e2240017f1ba57d4ac2986547"},"breadcrumb":{"@id":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stampenmedia.se\/kampanj\/2020\/04\/29\/gokboet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"https:\/\/stampenmedia.se\/kampanj\/helagbg\/"},{"@type":"ListItem","position":2,"name":"Vecka 18 &#8211; G\u00f6kboet"}]},{"@type":"WebSite","@id":"https:\/\/stampenmedia.se\/kampanj\/#website","url":"https:\/\/stampenmedia.se\/kampanj\/","name":"Kampanj","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stampenmedia.se\/kampanj\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Person","@id":"https:\/\/stampenmedia.se\/kampanj\/#\/schema\/person\/3d717e3e2240017f1ba57d4ac2986547","name":"Kampanj","image":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/secure.gravatar.com\/avatar\/19f7b289b694f164f9db9137f0738b2d73f6edf4cf60aa01f4dbc20313e57eb3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/19f7b289b694f164f9db9137f0738b2d73f6edf4cf60aa01f4dbc20313e57eb3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/19f7b289b694f164f9db9137f0738b2d73f6edf4cf60aa01f4dbc20313e57eb3?s=96&d=mm&r=g","caption":"Kampanj"},"url":"https:\/\/stampenmedia.se\/kampanj\/author\/kampanj\/"}]}},"_links":{"self":[{"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/posts\/18494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/comments?post=18494"}],"version-history":[{"count":2,"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/posts\/18494\/revisions"}],"predecessor-version":[{"id":18498,"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/posts\/18494\/revisions\/18498"}],"wp:attachment":[{"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/media?parent=18494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/categories?post=18494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stampenmedia.se\/kampanj\/wp-json\/wp\/v2\/tags?post=18494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}